{"id":2106,"date":"2017-03-31T08:34:32","date_gmt":"2017-03-31T08:34:32","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=2106"},"modified":"2017-03-31T08:34:32","modified_gmt":"2017-03-31T08:34:32","slug":"pi-sky-vi-die-empfangsstationen","status":"publish","type":"post","link":"http:\/\/wp.andreas.bieri.name\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/","title":{"rendered":"Pi-in-the-Sky VI: Die Bodenstationen"},"content":{"rendered":"<h4>Einleitung<\/h4>\n<p>(Ein Blog\u00a0in der Serie \u00fcber Stratosph\u00e4ren-Ballonmissionen, hier <a href=\"http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2016\/11\/20\/sdr-sharp-und-dl-fldigi-im-einsatz\/\" target=\"_blank\">zum Start der Serie<\/a>)<\/p>\n<p>Die Nutzlast ist gebaut, den Ballon und das Gas haben wir vielleicht auch schon, die Sendemodule und die Sensoren sind konfiguriert und getestet&#8230;vergessen wir aber nicht, dass es auch Empfangsstationen braucht! Die Empfangsanlagen k\u00f6nnen vielf\u00e4ltige Formen annehmen:<\/p>\n<ul>\n<li>eine feste Bodenfunkstation z.B. eines Amateurfunkers oder\u00a0-Vereins mit grossen, allenfalls drehbaren\u00a0Richtantennen (manuell\/automatisch)<\/li>\n<li>eine\u00a0Web SDR Station, Beispiel <a href=\"http:\/\/websdr.ewi.utwente.nl:8901\/\" target=\"_blank\">Enschede<\/a>\u00a0oder <a href=\"http:\/\/cambs-sdr.no-ip.org:8901\/\" target=\"_blank\">Peterborough<\/a>\u00a0oder <a href=\"http:\/\/websdr.suws.org.uk\/\" target=\"_blank\">Farnham<\/a>. Dort gibt es auch ein LoRa Gateway (<a href=\"https:\/\/philcrump.co.uk\/Main_Page\" target=\"_blank\">Phil Crump<\/a>)<\/li>\n<li>ein Laptop mit SDR Stick zuhause oder mobil (im Auto)<\/li>\n<li>eine portable <a href=\"http:\/\/www.lutz-electronics.ch\/amateurfunk\/sota-2\/\" target=\"_blank\">SOTA Station<\/a> mit einer\u00a0Richtantenne in der\u00a0Hand<\/li>\n<\/ul>\n<p>Es sind vielf\u00e4ltige Kombinationen denkbar, weshalb ich hier Bestandteile und Ideen beschreiben m\u00f6chte und nicht fertige Anlagen. Fangen wir &#8222;oben&#8220; an, bei den Antennen.<\/p>\n<p>&nbsp;<\/p>\n<h4>Antennen<\/h4>\n<p>An einer ortsfesten Anlage wird man nat\u00fcrlich ganz andere Antennen anschliessen k\u00f6nnen, als an einer mobilen im Auto. F\u00fcr Ballons werden mit Vorteile die folgenden Antennen eingesetzt (jede andere geht nat\u00fcrlich auch mehr oder weniger gut). Die kurze Wendelantenne oder Gummiwurst, die mit vielen SDR Sticks migeliefert wird, ist meistens die schlechteste Wahl.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.aorusa.com\/antennas\/pdf\/da3200_catalog.pdf\" target=\"_blank\">Discone:<\/a> diese Breitbandantennen haben einen flachen Abstrahlwinkel, w\u00e4ren also schlecht, wenn der Ballon direkt \u00fcber Kopf ist. Bei einer max. H\u00f6he von ca. 30km ist man aber schnell weit genug weg, sodass der Winkel weniger als 45 Grad\u00a0betr\u00e4gt. Discone Antennen decken einen grossen Frequenzbereich ab (typ. 100MHz-3GHz), sind aber weniger effizient als andere spezialisierte Antennen \u00a0und h\u00e4ufig auch sehr sperrig.<\/li>\n<li>\u00c4hnlich wie f\u00fcr Satellitenempfang\u00a0kann\u00a0eine quadrifilare Helix (<a href=\"https:\/\/www.youtube.com\/watch?v=eVI2qv7pv88\" target=\"_blank\">QFH<\/a>)\u00a0 oder eine Turnstile verwendet werden<\/li>\n<li>Vertikaler Rundstrahler wie diese <a href=\"http:\/\/www.lutz-electronics.ch\/amateurfunk\/antennen-und-zubehoer\/diamond-x-5000\/\" target=\"_blank\">Diamond X5000 (1.8m lang)<\/a>\u00a0oder <a href=\"http:\/\/radio-laden.ch\/contents\/de-ch\/d68_stationsantennen.html\" target=\"_blank\">diese Diamond<\/a><\/li>\n<li>Dipol &#8211; Antennen k\u00f6nnen schon mit kleinen Abmessungen eiffizient sein und sind schnell aufgebaut<\/li>\n<li>Yagi-Richtantennen sind die erste Wahl bei der genauen Richtungs-Ortung. Ein Spezialfall ist die <a href=\"https:\/\/de.wikipedia.org\/wiki\/HB9CV-Antenne\" target=\"_blank\">HB9CV Antenne<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>Kleine Galerie meiner eigenen Antennen<\/h4>\n<p>Im Laufe der Jahre haben sich so einige Antennen bei mir angesammelt. Leider kann ich an meinem jetzigen Wohnort kaum mehr grosse Antennen aufbauen wie fr\u00fcher in meinem eigenen Estrich. So habe ich\u00a0 mich auf h\u00f6here Frequenzen (=kleinere Antennen) und mehr digitale Funkerei verlegt.<\/p>\n<p>Ein paar kleine Antennen resp. Rohmaterial f\u00fcr 434MHz und 870MHz<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2651\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg\" alt=\"\" width=\"555\" height=\"326\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg 2212w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/stick-antennen-300x176.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/stick-antennen-768x451.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/stick-antennen-1024x602.jpg 1024w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/><\/p>\n<p>AOR Discone 5000, zusammengebaut <a href=\"http:\/\/www.aorusa.com\/antennas\/pdf\/da3200_catalog.pdf\" target=\"_blank\">\u00e4hnlich zu dieser.<\/a><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2602\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/AOR-Diskone.jpg\" alt=\"\" width=\"557\" height=\"283\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/AOR-Diskone.jpg 2515w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/AOR-Diskone-300x152.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/AOR-Diskone-768x390.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/AOR-Diskone-1024x520.jpg 1024w\" sizes=\"(max-width: 557px) 100vw, 557px\" \/><\/p>\n<p>Ein 144MHz\/430MHz Dipol, zerlegbar f\u00fcr den Rucksack<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2603\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/Wimo-Duobanddipol.jpg\" alt=\"\" width=\"556\" height=\"157\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/Wimo-Duobanddipol.jpg 2392w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/Wimo-Duobanddipol-300x85.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/Wimo-Duobanddipol-768x217.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/Wimo-Duobanddipol-1024x289.jpg 1024w\" sizes=\"(max-width: 556px) 100vw, 556px\" \/><\/p>\n<p>Eine MP1 &#8222;Superantenne&#8220;. F\u00fcr 2m\/70cm braucht man nur den Teleskop-Stab.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2604\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/MP1.jpg\" alt=\"\" width=\"551\" height=\"626\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/MP1.jpg 1835w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/MP1-264x300.jpg 264w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/MP1-768x872.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/MP1-902x1024.jpg 902w\" sizes=\"(max-width: 551px) 100vw, 551px\" \/><\/p>\n<p>Eine HB9CV Richtantenne f\u00fcr 2m, zerlegbar f\u00fcr den Rucksack<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2605\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/HB9CV.jpg\" alt=\"\" width=\"558\" height=\"204\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/HB9CV.jpg 2321w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/HB9CV-300x110.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/HB9CV-768x281.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/HB9CV-1024x375.jpg 1024w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/p>\n<p>Eine kombinierte 2m\/70cm Richtantenne, ebenfals rucksacktauglich zerlegbar, hier in zusammengeschraubtem Zustand. Die gr\u00f6sste L\u00e4nge ist ca. 90cm. Speziell: nur 1 Anschluss gemeinsam f\u00fcr beide Teilantennen.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2652\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/sota2band-aufgebaut.jpg\" alt=\"\" width=\"547\" height=\"360\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/sota2band-aufgebaut.jpg 2410w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/sota2band-aufgebaut-300x198.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/sota2band-aufgebaut-768x506.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/sota2band-aufgebaut-1024x675.jpg 1024w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/><\/p>\n<p>Eine 2m\/70cm Stationsantenne, vertikaler Rundstahler (&#8222;Blindenstock&#8220;). Sendetauglich bis ca. 200W, L\u00e4nge 1.20m.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2653\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/VX30.jpg\" alt=\"\" width=\"547\" height=\"119\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/VX30.jpg 2491w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/VX30-300x65.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/VX30-768x167.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/VX30-1024x223.jpg 1024w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>Montagematerial<\/h4>\n<p>Tipp: Antennen sollten m\u00f6glichst hoch aufgestellt werden. Dabei kann ein <a href=\"http:\/\/www.r-g.de\/wiki\/Gebrauchshinweise_f%C3%BCr_den_Teleskop-Tower\" target=\"_blank\">Glasfasermast<\/a> helfen (bis ca. 10m hoch!).<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2655\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/spieth-mast.jpg\" alt=\"\" width=\"551\" height=\"277\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/spieth-mast.jpg 661w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/spieth-mast-300x151.jpg 300w\" sizes=\"(max-width: 551px) 100vw, 551px\" \/><\/p>\n<p>Die ca. 1m langen\u00a0Elemente k\u00f6nnen ohne Werkzeug zusammengedreht werden. Der Mast ist hohl, das Kabel kann im Innern heruntergef\u00fchrt werden.<\/p>\n<p>&nbsp;<\/p>\n<h4>Pre-Selector, Filter<\/h4>\n<p>St\u00f6rende Signale k\u00f6nnen mit einem Filter (Bandpassfilter) ausgefiltert werden. Dies kann bei Radiosendern etc. n\u00f6tig werden, insbesondere, wenn die schwachen Signale noch mit einem Empfangsverst\u00e4rker verst\u00e4rkt werden sollen. Starke Signale \u00fcbersteuern sonst den Empf\u00e4nger und es ist nichts gewonnen. Fertige Filter von \u00a0<a href=\"https:\/\/www.minicircuits.com\/\" target=\"_blank\">Mini Circuits<\/a>\u00a0oder anderen Prof-Anbietern sind teilweise sehr teuer in h\u00f6heren Frequenzbereichen. F\u00fcr die Kurzwellenb\u00e4nder gibt es <a href=\"http:\/\/www.qrp-labs.com\/bpfkit.html\" target=\"_blank\">zahlbare Bandpassfilter\u00a0bei QRP Labs<\/a>.<\/p>\n<p>Ich habe mir einige kleine SAW Filter gebaut, die Bestandteile sind:<\/p>\n<ul>\n<li><a href=\"https:\/\/oshpark.com\/shared_projects\/bEZ5D9a5\" target=\"_blank\">Filterboard bei OSH Park<\/a>\u00a0oder\u00a0<a href=\"https:\/\/oshpark.com\/shared_projects\/m8jALd9p\" target=\"_blank\">433 MHz Filter <\/a><\/li>\n<li>Passende Filter gibt es bei <a href=\"http:\/\/wireless.murata.com\/eng\/products\/saw-components-for-non-mobile\/filters\/where\/rfm-freq-slider\/144,144.html\" target=\"_blank\">Murata<\/a> und <a href=\"http:\/\/www.abracon.com\/products.php?search=deF\" target=\"_blank\">Abracon<\/a><\/li>\n<\/ul>\n<p>Hier ein Bild und die Messung der Durchlasskurve:<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2608\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/SAW-Filter.jpg\" alt=\"\" width=\"610\" height=\"303\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SAW-Filter.jpg 874w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SAW-Filter-300x149.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SAW-Filter-768x381.jpg 768w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2609\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/SAW-Filter.png\" alt=\"\" width=\"606\" height=\"364\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SAW-Filter.png 800w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SAW-Filter-300x180.png 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SAW-Filter-768x461.png 768w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/><\/p>\n<p>Die Wirkung der Filter kann mit einem SDR-Stick und einer Rauschquelle gemessen werden:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.rtl-sdr.com\/?s=noise+source\" target=\"_blank\">Messungen mit einer Rauschquelle (RTL-SDR)<\/a><\/li>\n<li>Hintergrundinfos zum Rauschen\u00a0<a href=\"http:\/\/www.rtl-sdr.com\/?s=noise\" target=\"_blank\">Tutorial: Measuring filter characteristics and antenna VSWR with an RTL-SDR and noise source<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>Vorverst\u00e4rker (Low noise amplifier)<\/h4>\n<p>Schwache Signale sollten in der Regel direkt an der Antenne verst\u00e4rkt werden, damit diese nicht im Rauschnebel von PC, Empf\u00e4nger etc. untergehen. Man kennt dieses Prinzip von den Satellitenempf\u00e4nger: der Kolben vorne in der Satellitensch\u00fcssel enth\u00e4lt auch einen rauscharmen Vorverst\u00e4rker, eben einen <em>LNA<\/em> (Low-Noise Amplifier). In jedem Prospekt f\u00fcr Sat-Empfang findet man diesen Ausdruck.<\/p>\n<p>Auch hier kann man viel Geld ausgeben.<\/p>\n<ul>\n<li>Profi: <a href=\"http:\/\/shop.kuhne-electronic.de\/kuhne\/de\/shop\/empfangsverstaerker\/\" target=\"_blank\">Breitband VV und Filter von Kuhne<\/a>. Beispiel:\u00a00515 A\/B von 5 bis 5&#8217;000 MHz &#8211; <a href=\"https:\/\/www.kuhne-electronic.de\/funk\/de\/shop\/produkte\/prof-empfangsverst\/KU+LNA+BB+05152+A+SMA++Breitband+Vorverstaerker\/?card=1668\" target=\"_blank\">neue Version<\/a><\/li>\n<li>Semi-Profi: <a href=\"http:\/\/www.dg0ve.de\/produkte.htm\" target=\"_blank\">DG0VE UF Baugruppen<\/a><\/li>\n<li>Hobby-vertr\u00e4glich: <a href=\"http:\/\/lna4all.blogspot.ch\/\" target=\"_blank\">LNA for all &#8211; Low Noise Amplifier for many applications from 28 MHz to 2500 MHz <\/a>mit guten Erkl\u00e4rungen f\u00fcr Eigenbauprojekte wie Bias-T. Verkauft diese auch (erw\u00e4hnt bei RTL-SDR.com)<\/li>\n<li>Selbstbau: <a href=\"https:\/\/oshpark.com\/shared_projects\/1LKMh6Ey\" target=\"_blank\">LNA mit Mini Circuits Modul bei OHS<\/a><\/li>\n<\/ul>\n<p>Ich habe mir einige LNA aus China gekauft, meist unter 20.- Einer hat einen eingebauten 432MHz Filter drin:<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2612\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/LNAmitFilter.jpg\" alt=\"\" width=\"363\" height=\"137\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNAmitFilter.jpg 1301w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNAmitFilter-300x113.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNAmitFilter-768x290.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNAmitFilter-1024x386.jpg 1024w\" sizes=\"(max-width: 363px) 100vw, 363px\" \/><\/p>\n<p>Hier die Messung. Die Verst\u00e4rkung betr\u00e4gt \u00fcber 30dBm (Faktor 1000 Leistung) und die Bandbreite &lt; 25MHz.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2613\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/LNA-Filter-Ali.jpg\" alt=\"\" width=\"647\" height=\"388\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNA-Filter-Ali.jpg 800w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNA-Filter-Ali-300x180.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNA-Filter-Ali-768x461.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/p>\n<p>Beim <a href=\"http:\/\/wp.andreas.bieri.name\/myblog\/index.php\/2017\/02\/18\/outernet\/\" target=\"_blank\">Outernet Empf\u00e4nger Kit <\/a>ist ebenfalls ein breitbandiger LNA enthalten. Den besten Eindruck von allen macht mir aber der LNA4ALL (s. oben)<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2611\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/LNA4ALL.jpg\" alt=\"\" width=\"402\" height=\"208\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNA4ALL.jpg 960w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNA4ALL-300x155.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/LNA4ALL-768x398.jpg 768w\" sizes=\"(max-width: 402px) 100vw, 402px\" \/><\/p>\n<p>Hier ein Test: Im SDR# wurde der Gain auf 0 reduziert. Ein Radiosender wurde mit dem LNA deutlich empfangen, ohne nicht.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2629\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/LNA4ALL-test3.jpg\" alt=\"\" width=\"880\" height=\"256\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test3.jpg 2493w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test3-300x87.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test3-768x223.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test3-1024x298.jpg 1024w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2628\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/LNA4ALL-test2.jpg\" alt=\"\" width=\"880\" height=\"273\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test2.jpg 2489w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test2-300x93.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test2-768x239.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test2-1024x318.jpg 1024w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>LNA brauchen eine Speisung. Am einfachsten schickt man diese Spannung auf dem Kabel mit und koppelt sie aus (Bias-T). Die neuen Versionen V3 \u00a0der RTL SDR Sticks haben diese M\u00f6glichkeit bereits eingebaut (Modell TCXO+BIAS T+HF). Die Spannung wird\u00a0SW aktiviert). Mit den 5V kann z.B. der LNA4ALL gespiesen werden (richtiges Modell vorausgesetzt).<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2614\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/SDRStick.jpg\" alt=\"\" width=\"632\" height=\"238\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SDRStick.jpg 1458w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SDRStick-300x113.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SDRStick-768x289.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/SDRStick-1024x386.jpg 1024w\" sizes=\"(max-width: 632px) 100vw, 632px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2627\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/LNA4ALL-test1.jpg\" alt=\"\" width=\"635\" height=\"186\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test1.jpg 2196w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test1-300x88.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test1-768x225.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/LNA4ALL-test1-1024x300.jpg 1024w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4><\/h4>\n<h4>Vom USB Stick zum PC<\/h4>\n<p>Man sollte den Stick m\u00f6glichst weit weg von der Rauschquelle\u00a0PC platzieren, evtl. mit einem speziell langen USB-Kabel. Man achte aber auf eine gute Schirmung und Entst\u00f6rung wie bei diesem Kabel (Ferrit an beiden Kabelenden):<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2615\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/12\/USB.jpg\" alt=\"\" width=\"635\" height=\"202\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/USB.jpg 2412w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/USB-300x95.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/USB-768x244.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/12\/USB-1024x325.jpg 1024w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Empfangsbeispiel: APRS Gateway<\/h4>\n<p>Im meinem G\u00e4stezimmer habe ich den PITS mit 5m d\u00e4mpfungsarmen H-155 Kabel an den kleinen Dipol (2. Bild in der Antennengalerie) angeschlossen:<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-2705 aligncenter\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/zimmer-pits-station.jpg\" alt=\"\" width=\"463\" height=\"614\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/zimmer-pits-station.jpg 1166w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/zimmer-pits-station-226x300.jpg 226w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/zimmer-pits-station-768x1018.jpg 768w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/zimmer-pits-station-773x1024.jpg 773w\" sizes=\"(max-width: 463px) 100vw, 463px\" \/><\/p>\n<p>und konnte damit das APRS-Gateway auf dem Schilthorn erreichen. Meistens kommt ein anderes Gateway vorher zum Zug, aber es w\u00fcrde reichen. Die Antenne ist im Zimmer mit Sicht nach Osten; eine direkte Sichtverbindung zum Schilthorn gibt es (knapp) nicht.<\/p>\n<p><img loading=\"lazy\" class=\"size-full wp-image-2704 aligncenter\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/hb9tss-direkt.jpg\" alt=\"\" width=\"806\" height=\"637\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/hb9tss-direkt.jpg 806w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/hb9tss-direkt-300x237.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2017\/03\/hb9tss-direkt-768x607.jpg 768w\" sizes=\"(max-width: 806px) 100vw, 806px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Auswahl der Software<\/h4>\n<p>In den vorangegangenen Blogs habe ich das Software-Instrumentarium skizziert (Auswahl):<\/p>\n<ul>\n<li>SDRsharp f\u00fcr die Decodierung vom Stick<\/li>\n<li>Virtual Audio Cable<\/li>\n<li>dl-fldigi f\u00fcr RTTY inkl. Bilder. Alternativen wie\u00a0MixW, Multi-PSK\u00a0k\u00f6nnnen RTTY decodieren, haben aber\u00a0keine Anbindung an den habhub\u00a0Server<\/li>\n<li>Direwolf f\u00fcr die Decodierung von APRS<\/li>\n<li>APRSIS32 f\u00fcr die Darstellung von APRS Daten<\/li>\n<\/ul>\n<p>LoRA Decodierung erfordert ein Mikrocontroller-System zur Ansteuerung der LoRA Module. Daf\u00fcr entf\u00e4llt der SDR Stick und jede\u00a0andere Software.<\/p>\n<p>Auf Smartphones ist Empfang resp. Lokalisierung mit diesen Apps m\u00f6glich:<\/p>\n<ul>\n<li><a href=\"https:\/\/aprsdroid.org\/\" target=\"_blank\">APRSDroid<\/a><\/li>\n<li><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.brejza.matt.habmodem&amp;hl=de\" target=\"_blank\">HAB Tracker and Modem<\/a><\/li>\n<li><a href=\"http:\/\/www.mobilinkd.com\/\" target=\"_blank\">Mobilinkd<\/a>: Bluetooth TNC Anbindung an Handfunkger\u00e4t<\/li>\n<li><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.pexat.habhub.chasecartr\" target=\"_blank\">Habhub Chase Car Tracker <\/a><\/li>\n<\/ul>\n<p>Die Daten landen schliesslich im\u00a0Habhub oder in einem Sensor-Netzwerk wie<\/p>\n<ul>\n<li><a href=\"https:\/\/ukhas.net\/\" target=\"_blank\">A simple wireless network aimed for use with low power licence exempt wireless modules.<\/a><\/li>\n<li><a href=\"https:\/\/www.thethingsnetwork.org\/\" target=\"_blank\">The Things Network<\/a><\/li>\n<\/ul>\n<p>Und jetzt: Viel Spass beim\u00a0 Bauen und viel Erfolg!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einleitung (Ein Blog\u00a0in der Serie \u00fcber Stratosph\u00e4ren-Ballonmissionen, hier zum Start der Serie) Die Nutzlast ist gebaut, den Ballon und das Gas haben wir vielleicht auch schon, die Sendemodule und die Sensoren sind konfiguriert und getestet&#8230;vergessen wir aber nicht, dass es auch Empfangsstationen braucht! Die Empfangsanlagen k\u00f6nnen vielf\u00e4ltige Formen annehmen: eine feste Bodenfunkstation z.B. eines Amateurfunkers [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,11,12],"tags":[48,94,95,97],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pi-in-the-Sky VI: Die Bodenstationen - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi-in-the-Sky VI: Die Bodenstationen - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Einleitung (Ein Blog\u00a0in der Serie \u00fcber Stratosph\u00e4ren-Ballonmissionen, hier zum Start der Serie) Die Nutzlast ist gebaut, den Ballon und das Gas haben wir vielleicht auch schon, die Sendemodule und die Sensoren sind konfiguriert und getestet&#8230;vergessen wir aber nicht, dass es auch Empfangsstationen braucht! Die Empfangsanlagen k\u00f6nnen vielf\u00e4ltige Formen annehmen: eine feste Bodenfunkstation z.B. eines Amateurfunkers [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-31T08:34:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\",\"url\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg\",\"contentUrl\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#webpage\",\"url\":\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/\",\"name\":\"Pi-in-the-Sky VI: Die Bodenstationen - Merkbar.\",\"isPartOf\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#primaryimage\"},\"datePublished\":\"2017-03-31T08:34:32+00:00\",\"dateModified\":\"2017-03-31T08:34:32+00:00\",\"author\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pi-in-the-Sky VI: Die Bodenstationen\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/wp.andreas.bieri.name\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pi-in-the-Sky VI: Die Bodenstationen - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/","og_locale":"de_DE","og_type":"article","og_title":"Pi-in-the-Sky VI: Die Bodenstationen - Merkbar.","og_description":"Einleitung (Ein Blog\u00a0in der Serie \u00fcber Stratosph\u00e4ren-Ballonmissionen, hier zum Start der Serie) Die Nutzlast ist gebaut, den Ballon und das Gas haben wir vielleicht auch schon, die Sendemodule und die Sensoren sind konfiguriert und getestet&#8230;vergessen wir aber nicht, dass es auch Empfangsstationen braucht! Die Empfangsanlagen k\u00f6nnen vielf\u00e4ltige Formen annehmen: eine feste Bodenfunkstation z.B. eines Amateurfunkers [&hellip;]","og_url":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/","og_site_name":"Merkbar.","article_published_time":"2017-03-31T08:34:32+00:00","og_image":[{"url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin","Gesch\u00e4tzte Lesezeit":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website","url":"https:\/\/wp.andreas.bieri.name\/myblog\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#primaryimage","inLanguage":"de","url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg","contentUrl":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2017\/03\/stick-antennen.jpg"},{"@type":"WebPage","@id":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#webpage","url":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/","name":"Pi-in-the-Sky VI: Die Bodenstationen - Merkbar.","isPartOf":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#primaryimage"},"datePublished":"2017-03-31T08:34:32+00:00","dateModified":"2017-03-31T08:34:32+00:00","author":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/52.29.166.97\/myblog\/2017\/03\/31\/pi-sky-vi-die-empfangsstationen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wp.andreas.bieri.name\/myblog\/"},{"@type":"ListItem","position":2,"name":"Pi-in-the-Sky VI: Die Bodenstationen"}]},{"@type":"Person","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/wp.andreas.bieri.name\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts\/2106"}],"collection":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/comments?post=2106"}],"version-history":[{"count":0,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts\/2106\/revisions"}],"wp:attachment":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/media?parent=2106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/categories?post=2106"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/tags?post=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}