{"id":267,"date":"2015-07-11T19:32:32","date_gmt":"2015-07-11T19:32:32","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=267"},"modified":"2015-07-11T19:32:32","modified_gmt":"2015-07-11T19:32:32","slug":"experimente-mit-einem-wifi-modul-esp8266","status":"publish","type":"post","link":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/","title":{"rendered":"Experimente mit einem WiFi-Modul ESP8266"},"content":{"rendered":"<p>Vor einigen Monaten habe ich auf dem Internet ein WiFi-Modul ESP-8266 ESP-01 entdeckt:<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-268\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-01.jpg\" alt=\"esp-01\" width=\"235\" height=\"201\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-01.jpg 727w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-01-300x257.jpg 300w\" sizes=\"(max-width: 235px) 100vw, 235px\" \/><\/p>\n<p>Insbesondere haben mich der ausserordentlich tiefe Preis von weniger als Fr. 5.&#8211; \/ Stck. und die Abmessungen von nur 15mm x 25mm inkl. Antenne interessiert. Ich bestellte mir 2 St\u00fcck, und die beiden Module wurden innert zwei Wochen prompt aus China geliefert. Ich war sehr gespannt, ob diese Module auch so funktionieren wie im Datenblatt beschrieben.<br \/>\nDie gr\u00f6sste Herausforderung war das Studium des Datenblattes, denn alles war in chinesischer Sprache. Aber wozu gibt es den Google-Translator J. Unterdessen ist die englische Version auch erh\u00e4ltlich. Auf diesem WiFi-Modul ist ein vollst\u00e4ndiger 2.5GHz TRX mit dem mit WLAN (802.11 b\/g\/n) kommuniziert werden kann und einen 32Bit Prozessor, der die Steuerung \u00fcbernimmt. Der Flash-Speicher von 512kByte kann selbst umprogrammiert werden. Bei der Lieferung ist bereits eine Software (Firmware) programmiert, die es erlaubt, das WiFi-Modul mit sogenannten AT-Befehlen zu parametrisieren. Unter dem AT-Befehlssatz versteht man einen Satz Befehle &#8211; urspr\u00fcnglich von der Firma Hayes Communications entwickelt und zum Industriestandard geworden, &#8211; zum Konfigurieren und Parametrieren von Modems . Die Zeichen &#8222;AT&#8220; stehen dabei f\u00fcr &#8222;attention&#8220; und m\u00fcssen vor jedem Befehl gesendet werden.<br \/>\nUm mit dem WiFi-Modul zu kommunizieren, ist ein USB zu TTL Adapter notwendig (mit \u201eFT232RL FTDI USB to TTL\u201c unter Ebay suchen). Wichtig ist dabei, dass das Modul mit 3.3V betrieben wird. Es gibt USB\/TTL Adapter die von 5V auf 3.3V umgestellt werden k\u00f6nnen.<br \/>\nDas WiFi-Modul vom Typ ESP-01 ist etwas schwierig, auf ein Breadbord zu stecken, weil es einen 2&#215;4 Stecker hat. Dazu gibt es aber gute Bastelvorschl\u00e4ge auf dem Internet oder auch fixfertige Adapter zu kaufen.<img loading=\"lazy\" class=\"aligncenter size-medium wp-image-271\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-02.jpg\" alt=\"esp-02\" width=\"300\" height=\"200\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-02.jpg 477w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-02-300x200.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Wenn man das Modul mit einem Terminalprogramm ansprechen kann, ist es auch m\u00f6glich, andere Software zu laden. Wer z.B. die Arduino Plattform kennt, kann diese Software-Entwicklungsumgebung mit dem ESP8266-Modul erweitern https:\/\/github.com\/esp8266\/Arduino. Es kann in C++ programmiert und dazu dieselben Arduino Libraries verwendet werden.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-269\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-03.jpg\" alt=\"esp-03\" width=\"614\" height=\"395\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-03.jpg 813w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-03-300x193.jpg 300w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-03-768x494.jpg 768w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/p>\n<p>Ich habe mit einigen wenigen Befehlen einen einfachen Netzwerk-Scanner programmiert.\u00a0Das Ergebnis sieht dann z.B. so aus und zeigt alle vom WiFi-Modul empfangenen AP (Access-Points):<br \/>\n<img loading=\"lazy\" class=\"aligncenter wp-image-270\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-04.jpg\" alt=\"esp-04\" width=\"376\" height=\"197\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-04.jpg 476w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2016\/03\/esp-04-300x157.jpg 300w\" sizes=\"(max-width: 376px) 100vw, 376px\" \/><\/p>\n<p>Das WiFi-Modul ESP8266 ist unterdessen so popul\u00e4r, dass man unz\u00e4hlige Foren und Bastelanleitungen auf dem Internet findet. Das Forum des Herstellers ist hier zu finden <a href=\"http:\/\/bbs.espressif.com\/\">http:\/\/bbs.espressif.com\/<\/a>.\u00a0Auch im ESP8266 Community Forum http:\/\/www.esp8266.com\/ gibt es sehr viele Informationen und Programmbeispiele. Wer eine deutsche Seite sucht, wird hier <a href=\"https:\/\/www.mikrocontroller.net\/articles\/ESP8266\">https:\/\/www.mikrocontroller.net\/articles\/ESP8266<\/a> f\u00fcndig. Es w\u00fcrde mich freuen, wenn ich einige R\u00fcckmeldungen und Anregungen erhalten k\u00f6nnte, und dabei neue und interessante Anwendungen f\u00fcr den Amateurfunk entstehen w\u00fcrden. Ich denke da z.B. an die Fernsteuerung des Transceivers via CAT \u00fcber WiFi, die drahtlose Rotorsteuerung usw.<\/p>\n<p>(Beitrag von\u00a0Roland Elmiger)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor einigen Monaten habe ich auf dem Internet ein WiFi-Modul ESP-8266 ESP-01 entdeckt: Insbesondere haben mich der ausserordentlich tiefe Preis von weniger als Fr. 5.&#8211; \/ Stck. und die Abmessungen von nur 15mm x 25mm inkl. Antenne interessiert. Ich bestellte mir 2 St\u00fcck, und die beiden Module wurden innert zwei Wochen prompt aus China geliefert. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,2],"tags":[46,147],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Experimente mit einem WiFi-Modul ESP8266 - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experimente mit einem WiFi-Modul ESP8266 - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Vor einigen Monaten habe ich auf dem Internet ein WiFi-Modul ESP-8266 ESP-01 entdeckt: Insbesondere haben mich der ausserordentlich tiefe Preis von weniger als Fr. 5.&#8211; \/ Stck. und die Abmessungen von nur 15mm x 25mm inkl. Antenne interessiert. Ich bestellte mir 2 St\u00fcck, und die beiden Module wurden innert zwei Wochen prompt aus China geliefert. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-11T19:32:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-01.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\",\"url\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-01.jpg\",\"contentUrl\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-01.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#webpage\",\"url\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/\",\"name\":\"Experimente mit einem WiFi-Modul ESP8266 - Merkbar.\",\"isPartOf\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#primaryimage\"},\"datePublished\":\"2015-07-11T19:32:32+00:00\",\"dateModified\":\"2015-07-11T19:32:32+00:00\",\"author\":{\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wp.andreas.bieri.name\/myblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experimente mit einem WiFi-Modul ESP8266\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/wp.andreas.bieri.name\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experimente mit einem WiFi-Modul ESP8266 - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/","og_locale":"de_DE","og_type":"article","og_title":"Experimente mit einem WiFi-Modul ESP8266 - Merkbar.","og_description":"Vor einigen Monaten habe ich auf dem Internet ein WiFi-Modul ESP-8266 ESP-01 entdeckt: Insbesondere haben mich der ausserordentlich tiefe Preis von weniger als Fr. 5.&#8211; \/ Stck. und die Abmessungen von nur 15mm x 25mm inkl. Antenne interessiert. Ich bestellte mir 2 St\u00fcck, und die beiden Module wurden innert zwei Wochen prompt aus China geliefert. [&hellip;]","og_url":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/","og_site_name":"Merkbar.","article_published_time":"2015-07-11T19:32:32+00:00","og_image":[{"url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-01.jpg"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website","url":"https:\/\/wp.andreas.bieri.name\/myblog\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.andreas.bieri.name\/myblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#primaryimage","inLanguage":"de","url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-01.jpg","contentUrl":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/03\/esp-01.jpg"},{"@type":"WebPage","@id":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#webpage","url":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/","name":"Experimente mit einem WiFi-Modul ESP8266 - Merkbar.","isPartOf":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#primaryimage"},"datePublished":"2015-07-11T19:32:32+00:00","dateModified":"2015-07-11T19:32:32+00:00","author":{"@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/ec2-52-29-166-97.eu-central-1.compute.amazonaws.com\/myblog\/2015\/07\/11\/experimente-mit-einem-wifi-modul-esp8266\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wp.andreas.bieri.name\/myblog\/"},{"@type":"ListItem","position":2,"name":"Experimente mit einem WiFi-Modul ESP8266"}]},{"@type":"Person","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"https:\/\/wp.andreas.bieri.name\/myblog\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/wp.andreas.bieri.name\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts\/267"}],"collection":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/comments?post=267"}],"version-history":[{"count":0,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts\/267\/revisions"}],"wp:attachment":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/media?parent=267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/categories?post=267"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/tags?post=267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}