{"id":668,"date":"2015-04-18T19:43:19","date_gmt":"2015-04-18T19:43:19","guid":{"rendered":"http:\/\/wp.andreas.bieri.name\/myblog\/?p=668"},"modified":"2015-04-18T19:43:19","modified_gmt":"2015-04-18T19:43:19","slug":"fundstelle-internet-zeichenpapier","status":"publish","type":"post","link":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/","title":{"rendered":"Fundstelle Internet: Zeichenpapier"},"content":{"rendered":"<p>Immer wieder n\u00fctzlich: vorbedrucktes Zeichenpapier in diversen Mustern f\u00fcr Agenden, Notizen oder f\u00fcr Rechenbl\u00e4tter (Nomogramme) zum Herunterladen im PDF Format gibt es hier: <a href=\"http:\/\/incompetech.com\/graphpaper\">http:\/\/incompetech.com\/graphpaper<\/a>.<\/p>\n<p>Beispiel: A4 doppelt-logarithmisches Papier. Datei zum Herunteladen:\u00a0<a href=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2016\/04\/logarithmic-A4.pdf\" rel=\"\">logarithmic-A4<\/a>.<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-671\" src=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2014\/04\/loga4.png\" alt=\"loga4\" width=\"577\" height=\"821\" srcset=\"http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2014\/04\/loga4.png 577w, http:\/\/wp.andreas.bieri.name\/myblog\/wp-content\/uploads\/2014\/04\/loga4-211x300.png 211w\" sizes=\"(max-width: 577px) 100vw, 577px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immer wieder n\u00fctzlich: vorbedrucktes Zeichenpapier in diversen Mustern f\u00fcr Agenden, Notizen oder f\u00fcr Rechenbl\u00e4tter (Nomogramme) zum Herunterladen im PDF Format gibt es hier: http:\/\/incompetech.com\/graphpaper. Beispiel: A4 doppelt-logarithmisches Papier. Datei zum Herunteladen:\u00a0logarithmic-A4.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[88],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fundstelle Internet: Zeichenpapier - Merkbar.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundstelle Internet: Zeichenpapier - Merkbar.\" \/>\n<meta property=\"og:description\" content=\"Immer wieder n\u00fctzlich: vorbedrucktes Zeichenpapier in diversen Mustern f\u00fcr Agenden, Notizen oder f\u00fcr Rechenbl\u00e4tter (Nomogramme) zum Herunterladen im PDF Format gibt es hier: http:\/\/incompetech.com\/graphpaper. Beispiel: A4 doppelt-logarithmisches Papier. Datei zum Herunteladen:\u00a0logarithmic-A4.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkbar.\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-18T19:43:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2014\/04\/loga4.png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_blogadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"\/#website\",\"url\":\"\/\",\"name\":\"Merkbar.\",\"description\":\"IT, Elektronik und Mathematik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2014\/04\/loga4.png\",\"contentUrl\":\"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2014\/04\/loga4.png\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#webpage\",\"url\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/\",\"name\":\"Fundstelle Internet: Zeichenpapier - Merkbar.\",\"isPartOf\":{\"@id\":\"\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#primaryimage\"},\"datePublished\":\"2015-04-18T19:43:19+00:00\",\"dateModified\":\"2015-04-18T19:43:19+00:00\",\"author\":{\"@id\":\"\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\"},\"breadcrumb\":{\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundstelle Internet: Zeichenpapier\"}]},{\"@type\":\"Person\",\"@id\":\"\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d\",\"name\":\"wp_blogadmin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g\",\"caption\":\"wp_blogadmin\"},\"url\":\"http:\/\/wp.andreas.bieri.name\/myblog\/author\/wp_blogadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundstelle Internet: Zeichenpapier - Merkbar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/","og_locale":"de_DE","og_type":"article","og_title":"Fundstelle Internet: Zeichenpapier - Merkbar.","og_description":"Immer wieder n\u00fctzlich: vorbedrucktes Zeichenpapier in diversen Mustern f\u00fcr Agenden, Notizen oder f\u00fcr Rechenbl\u00e4tter (Nomogramme) zum Herunterladen im PDF Format gibt es hier: http:\/\/incompetech.com\/graphpaper. Beispiel: A4 doppelt-logarithmisches Papier. Datei zum Herunteladen:\u00a0logarithmic-A4.","og_url":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/","og_site_name":"Merkbar.","article_published_time":"2015-04-18T19:43:19+00:00","og_image":[{"url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2014\/04\/loga4.png"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"wp_blogadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Merkbar.","description":"IT, Elektronik und Mathematik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#primaryimage","inLanguage":"de","url":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2014\/04\/loga4.png","contentUrl":"http:\/\/wp.andreas.bieri.name\/wp-content\/uploads\/2014\/04\/loga4.png"},{"@type":"WebPage","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#webpage","url":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/","name":"Fundstelle Internet: Zeichenpapier - Merkbar.","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#primaryimage"},"datePublished":"2015-04-18T19:43:19+00:00","dateModified":"2015-04-18T19:43:19+00:00","author":{"@id":"\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d"},"breadcrumb":{"@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wp.andreas.bieri.name\/myblog\/2015\/04\/18\/fundstelle-internet-zeichenpapier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"\/"},{"@type":"ListItem","position":2,"name":"Fundstelle Internet: Zeichenpapier"}]},{"@type":"Person","@id":"\/#\/schema\/person\/47691942dec3f2eb9d34bb8b5507870d","name":"wp_blogadmin","image":{"@type":"ImageObject","@id":"\/#personlogo","inLanguage":"de","url":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/d0dc804558b03f640b22e497ec010c9a?s=96&d=mm&r=g","caption":"wp_blogadmin"},"url":"http:\/\/wp.andreas.bieri.name\/myblog\/author\/wp_blogadmin\/"}]}},"_links":{"self":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts\/668"}],"collection":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":0,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/posts\/668\/revisions"}],"wp:attachment":[{"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/media?parent=668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/categories?post=668"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wp.andreas.bieri.name\/myblog\/wp-json\/wp\/v2\/tags?post=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}